{"id":1729,"date":"2023-09-12T07:38:01","date_gmt":"2023-09-12T05:38:01","guid":{"rendered":"http:\/\/elbavip.youelba.com\/accommodation\/quadrilocale\/"},"modified":"2026-03-03T14:32:20","modified_gmt":"2026-03-03T13:32:20","slug":"vierzimmerwohnung","status":"publish","type":"mphb_room_type","link":"https:\/\/www.elbavip.it\/de\/accommodation\/vierzimmerwohnung\/","title":{"rendered":"Vierzimmerwohnung"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1729\" class=\"elementor elementor-1729 elementor-403\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7165e143 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"7165e143\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;hoteller_ext_is_background_parallax&quot;:&quot;true&quot;,&quot;hoteller_ext_is_background_parallax_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.1,&quot;sizes&quot;:[]},&quot;hoteller_ext_is_background_backdrop&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_on_scroll&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-230a6a4e\" data-id=\"230a6a4e\" data-element_type=\"column\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-357efcf8 elementor-widget elementor-widget-heading\" data-id=\"357efcf8\" data-element_type=\"widget\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Vierzimmerwohnung<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-63075ccb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"63075ccb\" data-element_type=\"section\" data-settings=\"{&quot;hoteller_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_backdrop&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_on_scroll&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3a3607d4\" data-id=\"3a3607d4\" data-element_type=\"column\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3da9350 elementor-widget elementor-widget-text-editor\" data-id=\"3da9350\" data-element_type=\"widget\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Vierzimmerwohnung mit 6+1 Betten<\/strong>, intern auf zwei Ebenen verteilt. Untere Etage: Wohnzimmer mit Kochnische und Schlafsofa, gro\u00dfes Schlafzimmer mit Doppelbett, Schlafzimmer mit zwei Einzelbetten, m\u00f6blierter Balkon, Badezimmer. Obere Etage (Dachgeschoss): Schlafzimmer mit zwei Einzelbetten (mit Fenstert\u00fcr und kleinem Balkon), zweites Badezimmer.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2a7b0474\" data-id=\"2a7b0474\" data-element_type=\"column\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77ed4e elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"77ed4e\" data-element_type=\"widget\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.elbavip.it\/de\/kontakte\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt buchen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f99c0dd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f99c0dd\" data-element_type=\"section\" data-settings=\"{&quot;hoteller_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_backdrop&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_on_scroll&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-33aecfc3\" data-id=\"33aecfc3\" data-element_type=\"column\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21cda120 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"21cda120\" data-element_type=\"widget\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6bf5efc5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6bf5efc5\" data-element_type=\"section\" data-settings=\"{&quot;hoteller_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_backdrop&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_on_scroll&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6e441a8f\" data-id=\"6e441a8f\" data-element_type=\"column\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d75e248 elementor-widget elementor-widget-image-gallery\" data-id=\"d75e248\" data-element_type=\"widget\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-1729 gallery-columns-3 gallery-size-medium'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d75e248\" data-elementor-lightbox-title=\"app_quadrilocale_01-3592917061\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkxNywidXJsIjoiaHR0cHM6XC9cL3d3dy5lbGJhdmlwLml0XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNlwvYXBwX3F1YWRyaWxvY2FsZV8wMS0zNTkyOTE3MDYxLmpwZyIsInNsaWRlc2hvdyI6ImQ3NWUyNDgifQ%3D%3D\" href='https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_quadrilocale_01-3592917061.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_quadrilocale_01-3592917061-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_quadrilocale_01-3592917061-300x169.jpg 300w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_quadrilocale_01-3592917061-768x432.jpg 768w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_quadrilocale_01-3592917061-440x247.jpg 440w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_quadrilocale_01-3592917061.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d75e248\" data-elementor-lightbox-title=\"app_quadrilocale_02-1487443878\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkxOCwidXJsIjoiaHR0cHM6XC9cL3d3dy5lbGJhdmlwLml0XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNlwvYXBwX3F1YWRyaWxvY2FsZV8wMi0xNDg3NDQzODc4LmpwZyIsInNsaWRlc2hvdyI6ImQ3NWUyNDgifQ%3D%3D\" href='https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_quadrilocale_02-1487443878.jpg'><img decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_quadrilocale_02-1487443878-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_quadrilocale_02-1487443878-300x169.jpg 300w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_quadrilocale_02-1487443878-768x432.jpg 768w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_quadrilocale_02-1487443878-440x247.jpg 440w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_quadrilocale_02-1487443878.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d75e248\" data-elementor-lightbox-title=\"app_quadrilocale_04-2663882273\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkxOSwidXJsIjoiaHR0cHM6XC9cL3d3dy5lbGJhdmlwLml0XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNlwvYXBwX3F1YWRyaWxvY2FsZV8wNC0yNjYzODgyMjczLmpwZyIsInNsaWRlc2hvdyI6ImQ3NWUyNDgifQ%3D%3D\" href='https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_quadrilocale_04-2663882273.jpg'><img decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_quadrilocale_04-2663882273-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_quadrilocale_04-2663882273-300x169.jpg 300w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_quadrilocale_04-2663882273-768x432.jpg 768w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_quadrilocale_04-2663882273-440x247.jpg 440w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_quadrilocale_04-2663882273.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d75e248\" data-elementor-lightbox-title=\"app_trilocale_primo_03-685014975\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkyMCwidXJsIjoiaHR0cHM6XC9cL3d3dy5lbGJhdmlwLml0XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNlwvYXBwX3RyaWxvY2FsZV9wcmltb18wMy02ODUwMTQ5NzUuanBnIiwic2xpZGVzaG93IjoiZDc1ZTI0OCJ9\" href='https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_03-685014975.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_03-685014975-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_03-685014975-300x169.jpg 300w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_03-685014975-768x432.jpg 768w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_03-685014975-440x247.jpg 440w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_03-685014975.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d75e248\" data-elementor-lightbox-title=\"app_trilocale_primo_19-2926540596\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkyMSwidXJsIjoiaHR0cHM6XC9cL3d3dy5lbGJhdmlwLml0XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNlwvYXBwX3RyaWxvY2FsZV9wcmltb18xOS0yOTI2NTQwNTk2LmpwZyIsInNsaWRlc2hvdyI6ImQ3NWUyNDgifQ%3D%3D\" href='https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_19-2926540596.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_19-2926540596-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_19-2926540596-300x169.jpg 300w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_19-2926540596-768x432.jpg 768w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_19-2926540596-440x247.jpg 440w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_19-2926540596.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d75e248\" data-elementor-lightbox-title=\"app_trilocale_primo_16-2001692056\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkyMiwidXJsIjoiaHR0cHM6XC9cL3d3dy5lbGJhdmlwLml0XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNlwvYXBwX3RyaWxvY2FsZV9wcmltb18xNi0yMDAxNjkyMDU2LmpwZyIsInNsaWRlc2hvdyI6ImQ3NWUyNDgifQ%3D%3D\" href='https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_16-2001692056.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_16-2001692056-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_16-2001692056-300x169.jpg 300w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_16-2001692056-768x432.jpg 768w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_16-2001692056-440x247.jpg 440w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_16-2001692056.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d75e248\" data-elementor-lightbox-title=\"app_trilocale_primo_18-1657108394\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkyMywidXJsIjoiaHR0cHM6XC9cL3d3dy5lbGJhdmlwLml0XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNlwvYXBwX3RyaWxvY2FsZV9wcmltb18xOC0xNjU3MTA4Mzk0LmpwZyIsInNsaWRlc2hvdyI6ImQ3NWUyNDgifQ%3D%3D\" href='https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_18-1657108394.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_18-1657108394-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_18-1657108394-300x169.jpg 300w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_18-1657108394-768x432.jpg 768w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_18-1657108394-440x247.jpg 440w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_18-1657108394.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d75e248\" data-elementor-lightbox-title=\"app_trilocale_primo_01-1794209986\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkyNCwidXJsIjoiaHR0cHM6XC9cL3d3dy5lbGJhdmlwLml0XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNlwvYXBwX3RyaWxvY2FsZV9wcmltb18wMS0xNzk0MjA5OTg2LmpwZyIsInNsaWRlc2hvdyI6ImQ3NWUyNDgifQ%3D%3D\" href='https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_01-1794209986.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_01-1794209986-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_01-1794209986-300x169.jpg 300w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_01-1794209986-768x432.jpg 768w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_01-1794209986-440x247.jpg 440w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_01-1794209986.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d75e248\" data-elementor-lightbox-title=\"app_trilocale_primo_20-2293059802\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkyNSwidXJsIjoiaHR0cHM6XC9cL3d3dy5lbGJhdmlwLml0XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNlwvYXBwX3RyaWxvY2FsZV9wcmltb18yMC0yMjkzMDU5ODAyLmpwZyIsInNsaWRlc2hvdyI6ImQ3NWUyNDgifQ%3D%3D\" href='https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_20-2293059802.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_20-2293059802-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_20-2293059802-300x169.jpg 300w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_20-2293059802-768x432.jpg 768w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_20-2293059802-440x247.jpg 440w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_20-2293059802.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d75e248\" data-elementor-lightbox-title=\"app_trilocale_primo_04-571569830\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkyNiwidXJsIjoiaHR0cHM6XC9cL3d3dy5lbGJhdmlwLml0XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNlwvYXBwX3RyaWxvY2FsZV9wcmltb18wNC01NzE1Njk4MzAuanBnIiwic2xpZGVzaG93IjoiZDc1ZTI0OCJ9\" href='https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_04-571569830.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_04-571569830-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_04-571569830-300x169.jpg 300w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_04-571569830-768x432.jpg 768w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_04-571569830-440x247.jpg 440w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_04-571569830.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d75e248\" data-elementor-lightbox-title=\"app_trilocale_primo_17-3152372998\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkyNywidXJsIjoiaHR0cHM6XC9cL3d3dy5lbGJhdmlwLml0XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNlwvYXBwX3RyaWxvY2FsZV9wcmltb18xNy0zMTUyMzcyOTk4LmpwZyIsInNsaWRlc2hvdyI6ImQ3NWUyNDgifQ%3D%3D\" href='https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_17-3152372998.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_17-3152372998-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_17-3152372998-300x169.jpg 300w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_17-3152372998-768x432.jpg 768w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_17-3152372998-440x247.jpg 440w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_17-3152372998.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d75e248\" data-elementor-lightbox-title=\"app_trilocale_primo_15-4190134907\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkyOCwidXJsIjoiaHR0cHM6XC9cL3d3dy5lbGJhdmlwLml0XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNlwvYXBwX3RyaWxvY2FsZV9wcmltb18xNS00MTkwMTM0OTA3LmpwZyIsInNsaWRlc2hvdyI6ImQ3NWUyNDgifQ%3D%3D\" href='https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_15-4190134907.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_15-4190134907-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_15-4190134907-300x169.jpg 300w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_15-4190134907-768x432.jpg 768w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_15-4190134907-440x247.jpg 440w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_15-4190134907.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d75e248\" data-elementor-lightbox-title=\"app_trilocale_primo_05-4005262904\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkyOSwidXJsIjoiaHR0cHM6XC9cL3d3dy5lbGJhdmlwLml0XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNlwvYXBwX3RyaWxvY2FsZV9wcmltb18wNS00MDA1MjYyOTA0LmpwZyIsInNsaWRlc2hvdyI6ImQ3NWUyNDgifQ%3D%3D\" href='https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_05-4005262904.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_05-4005262904-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_05-4005262904-300x169.jpg 300w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_05-4005262904-768x432.jpg 768w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_05-4005262904-440x247.jpg 440w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_05-4005262904.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d75e248\" data-elementor-lightbox-title=\"app_trilocale_primo_02-3833495329\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkzMCwidXJsIjoiaHR0cHM6XC9cL3d3dy5lbGJhdmlwLml0XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNlwvYXBwX3RyaWxvY2FsZV9wcmltb18wMi0zODMzNDk1MzI5LmpwZyIsInNsaWRlc2hvdyI6ImQ3NWUyNDgifQ%3D%3D\" href='https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_02-3833495329.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_02-3833495329-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_02-3833495329-300x169.jpg 300w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_02-3833495329-768x432.jpg 768w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_02-3833495329-440x247.jpg 440w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_02-3833495329.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d75e248\" data-elementor-lightbox-title=\"app_quadrilocale_07-273193410\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkzMSwidXJsIjoiaHR0cHM6XC9cL3d3dy5lbGJhdmlwLml0XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNlwvYXBwX3F1YWRyaWxvY2FsZV8wNy0yNzMxOTM0MTAuanBnIiwic2xpZGVzaG93IjoiZDc1ZTI0OCJ9\" href='https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_quadrilocale_07-273193410.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_quadrilocale_07-273193410-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_quadrilocale_07-273193410-300x169.jpg 300w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_quadrilocale_07-273193410-768x432.jpg 768w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_quadrilocale_07-273193410-440x247.jpg 440w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_quadrilocale_07-273193410.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d75e248\" data-elementor-lightbox-title=\"app_quadrilocale_03-2483197752\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkzMiwidXJsIjoiaHR0cHM6XC9cL3d3dy5lbGJhdmlwLml0XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wNlwvYXBwX3F1YWRyaWxvY2FsZV8wMy0yNDgzMTk3NzUyLmpwZyIsInNsaWRlc2hvdyI6ImQ3NWUyNDgifQ%3D%3D\" href='https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_quadrilocale_03-2483197752.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_quadrilocale_03-2483197752-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_quadrilocale_03-2483197752-300x169.jpg 300w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_quadrilocale_03-2483197752-768x432.jpg 768w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_quadrilocale_03-2483197752-440x247.jpg 440w, https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_quadrilocale_03-2483197752.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-402f811b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"402f811b\" data-element_type=\"section\" data-settings=\"{&quot;hoteller_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_backdrop&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_on_scroll&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-454fe0d0\" data-id=\"454fe0d0\" data-element_type=\"column\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-75a4e23b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"75a4e23b\" data-element_type=\"widget\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Vierzimmerwohnung Vierzimmerwohnung mit 6+1 Betten, intern auf zwei Ebenen verteilt. Untere Etage: Wohnzimmer mit Kochnische und Schlafsofa, gro\u00dfes Schlafzimmer mit Doppelbett, Schlafzimmer mit zwei Einzelbetten, m\u00f6blierter Balkon, Badezimmer. Obere Etage (Dachgeschoss): Schlafzimmer mit zwei Einzelbetten (mit Fenstert\u00fcr und kleinem Balkon), [&hellip;]<\/p>\n","protected":false},"featured_media":2928,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","mphb_room_type_category":[],"mphb_room_type_tag":[],"mphb_room_type_facility":[],"class_list":["post-1729","mphb_room_type","type-mphb_room_type","status-publish","has-post-thumbnail","hentry","mphb-room-type-adults-1","mphb-room-type-children-0",""],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vierzimmerwohnung - CAV Elbavip<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.elbavip.it\/de\/accommodation\/vierzimmerwohnung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vierzimmerwohnung - CAV Elbavip\" \/>\n<meta property=\"og:description\" content=\"Vierzimmerwohnung Vierzimmerwohnung mit 6+1 Betten, intern auf zwei Ebenen verteilt. Untere Etage: Wohnzimmer mit Kochnische und Schlafsofa, gro\u00dfes Schlafzimmer mit Doppelbett, Schlafzimmer mit zwei Einzelbetten, m\u00f6blierter Balkon, Badezimmer. Obere Etage (Dachgeschoss): Schlafzimmer mit zwei Einzelbetten (mit Fenstert\u00fcr und kleinem Balkon), [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.elbavip.it\/de\/accommodation\/vierzimmerwohnung\/\" \/>\n<meta property=\"og:site_name\" content=\"CAV Elbavip\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-03T13:32:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_15-4190134907.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"562\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.elbavip.it\/de\/accommodation\/vierzimmerwohnung\/\",\"url\":\"https:\/\/www.elbavip.it\/de\/accommodation\/vierzimmerwohnung\/\",\"name\":\"Vierzimmerwohnung - CAV Elbavip\",\"isPartOf\":{\"@id\":\"https:\/\/www.elbavip.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.elbavip.it\/de\/accommodation\/vierzimmerwohnung\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.elbavip.it\/de\/accommodation\/vierzimmerwohnung\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_15-4190134907.jpg\",\"datePublished\":\"2023-09-12T05:38:01+00:00\",\"dateModified\":\"2026-03-03T13:32:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.elbavip.it\/de\/accommodation\/vierzimmerwohnung\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.elbavip.it\/de\/accommodation\/vierzimmerwohnung\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.elbavip.it\/de\/accommodation\/vierzimmerwohnung\/#primaryimage\",\"url\":\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_15-4190134907.jpg\",\"contentUrl\":\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_15-4190134907.jpg\",\"width\":1000,\"height\":562},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.elbavip.it\/de\/accommodation\/vierzimmerwohnung\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.elbavip.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unterkunftsarten\",\"item\":\"https:\/\/www.elbavip.it\/de\/accommodation\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vierzimmerwohnung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.elbavip.it\/#website\",\"url\":\"https:\/\/www.elbavip.it\/\",\"name\":\"CAV Appartamenti Elbavip\",\"description\":\"Appartamenti per vacanze all&#039;Isola d&#039;Elba\",\"publisher\":{\"@id\":\"https:\/\/www.elbavip.it\/#organization\"},\"alternateName\":\"Elba Vip CAV \u00e8 un residence immerso nel verde\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.elbavip.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.elbavip.it\/#organization\",\"name\":\"Elbavip\",\"alternateName\":\"Appartamenti per vacanze Elba Vip\",\"url\":\"https:\/\/www.elbavip.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.elbavip.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/04\/elba_vip.png\",\"contentUrl\":\"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/04\/elba_vip.png\",\"width\":280,\"height\":156,\"caption\":\"Elbavip\"},\"image\":{\"@id\":\"https:\/\/www.elbavip.it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vierzimmerwohnung - CAV Elbavip","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.elbavip.it\/de\/accommodation\/vierzimmerwohnung\/","og_locale":"de_DE","og_type":"article","og_title":"Vierzimmerwohnung - CAV Elbavip","og_description":"Vierzimmerwohnung Vierzimmerwohnung mit 6+1 Betten, intern auf zwei Ebenen verteilt. Untere Etage: Wohnzimmer mit Kochnische und Schlafsofa, gro\u00dfes Schlafzimmer mit Doppelbett, Schlafzimmer mit zwei Einzelbetten, m\u00f6blierter Balkon, Badezimmer. Obere Etage (Dachgeschoss): Schlafzimmer mit zwei Einzelbetten (mit Fenstert\u00fcr und kleinem Balkon), [&hellip;]","og_url":"https:\/\/www.elbavip.it\/de\/accommodation\/vierzimmerwohnung\/","og_site_name":"CAV Elbavip","article_modified_time":"2026-03-03T13:32:20+00:00","og_image":[{"width":1000,"height":562,"url":"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_15-4190134907.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.elbavip.it\/de\/accommodation\/vierzimmerwohnung\/","url":"https:\/\/www.elbavip.it\/de\/accommodation\/vierzimmerwohnung\/","name":"Vierzimmerwohnung - CAV Elbavip","isPartOf":{"@id":"https:\/\/www.elbavip.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.elbavip.it\/de\/accommodation\/vierzimmerwohnung\/#primaryimage"},"image":{"@id":"https:\/\/www.elbavip.it\/de\/accommodation\/vierzimmerwohnung\/#primaryimage"},"thumbnailUrl":"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_15-4190134907.jpg","datePublished":"2023-09-12T05:38:01+00:00","dateModified":"2026-03-03T13:32:20+00:00","breadcrumb":{"@id":"https:\/\/www.elbavip.it\/de\/accommodation\/vierzimmerwohnung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.elbavip.it\/de\/accommodation\/vierzimmerwohnung\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.elbavip.it\/de\/accommodation\/vierzimmerwohnung\/#primaryimage","url":"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_15-4190134907.jpg","contentUrl":"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/06\/app_trilocale_primo_15-4190134907.jpg","width":1000,"height":562},{"@type":"BreadcrumbList","@id":"https:\/\/www.elbavip.it\/de\/accommodation\/vierzimmerwohnung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.elbavip.it\/"},{"@type":"ListItem","position":2,"name":"Unterkunftsarten","item":"https:\/\/www.elbavip.it\/de\/accommodation\/"},{"@type":"ListItem","position":3,"name":"Vierzimmerwohnung"}]},{"@type":"WebSite","@id":"https:\/\/www.elbavip.it\/#website","url":"https:\/\/www.elbavip.it\/","name":"CAV Appartamenti Elbavip","description":"Appartamenti per vacanze all&#039;Isola d&#039;Elba","publisher":{"@id":"https:\/\/www.elbavip.it\/#organization"},"alternateName":"Elba Vip CAV \u00e8 un residence immerso nel verde","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.elbavip.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.elbavip.it\/#organization","name":"Elbavip","alternateName":"Appartamenti per vacanze Elba Vip","url":"https:\/\/www.elbavip.it\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.elbavip.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/04\/elba_vip.png","contentUrl":"https:\/\/www.elbavip.it\/wp-content\/uploads\/2025\/04\/elba_vip.png","width":280,"height":156,"caption":"Elbavip"},"image":{"@id":"https:\/\/www.elbavip.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.elbavip.it\/de\/wp-json\/wp\/v2\/mphb_room_type\/1729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elbavip.it\/de\/wp-json\/wp\/v2\/mphb_room_type"}],"about":[{"href":"https:\/\/www.elbavip.it\/de\/wp-json\/wp\/v2\/types\/mphb_room_type"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elbavip.it\/de\/wp-json\/wp\/v2\/comments?post=1729"}],"version-history":[{"count":5,"href":"https:\/\/www.elbavip.it\/de\/wp-json\/wp\/v2\/mphb_room_type\/1729\/revisions"}],"predecessor-version":[{"id":3311,"href":"https:\/\/www.elbavip.it\/de\/wp-json\/wp\/v2\/mphb_room_type\/1729\/revisions\/3311"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elbavip.it\/de\/wp-json\/wp\/v2\/media\/2928"}],"wp:attachment":[{"href":"https:\/\/www.elbavip.it\/de\/wp-json\/wp\/v2\/media?parent=1729"}],"wp:term":[{"taxonomy":"mphb_room_type_category","embeddable":true,"href":"https:\/\/www.elbavip.it\/de\/wp-json\/wp\/v2\/mphb_room_type_category?post=1729"},{"taxonomy":"mphb_room_type_tag","embeddable":true,"href":"https:\/\/www.elbavip.it\/de\/wp-json\/wp\/v2\/mphb_room_type_tag?post=1729"},{"taxonomy":"mphb_room_type_facility","embeddable":true,"href":"https:\/\/www.elbavip.it\/de\/wp-json\/wp\/v2\/mphb_room_type_facility?post=1729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}